{"id":2,"date":"2022-01-21T16:15:24","date_gmt":"2022-01-21T16:15:24","guid":{"rendered":"https:\/\/naturheilpraxis9645.live-website.com\/?page_id=2"},"modified":"2025-06-17T14:35:24","modified_gmt":"2025-06-17T14:35:24","slug":"homoeopathische-hausapotheke","status":"publish","type":"page","link":"https:\/\/naturheilpraxis-kerres.de\/en\/homoeopathische-hausapotheke\/","title":{"rendered":"Homeopathic Medicine Cabinet"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"2\" class=\"elementor elementor-2\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-00851d7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"00851d7\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-16b8cda\" data-id=\"16b8cda\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-810b812\" data-id=\"810b812\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e2d66ae elementor-widget elementor-widget-image\" data-id=\"e2d66ae\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/naturheilpraxis-kerres.de\/\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"104\" src=\"https:\/\/naturheilpraxis-kerres.de\/wp-content\/uploads\/2022\/03\/Kerres_Logo_mit_800px_RGB-300x104.png\" class=\"attachment-medium size-medium wp-image-1494\" alt=\"\" srcset=\"https:\/\/naturheilpraxis-kerres.de\/wp-content\/uploads\/2022\/03\/Kerres_Logo_mit_800px_RGB-300x104.png 300w, https:\/\/naturheilpraxis-kerres.de\/wp-content\/uploads\/2022\/03\/Kerres_Logo_mit_800px_RGB-768x265.png 768w, https:\/\/naturheilpraxis-kerres.de\/wp-content\/uploads\/2022\/03\/Kerres_Logo_mit_800px_RGB.png 800w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-25eea48\" data-id=\"25eea48\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1f566d6 elementor-section-full_width elementor-section-content-middle elementor-section-height-default elementor-section-height-default\" data-id=\"1f566d6\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-34dac20\" data-id=\"34dac20\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9bc3a56 elementor-nav-menu--dropdown-tablet elementor-nav-menu__text-align-aside elementor-nav-menu--toggle elementor-nav-menu--burger elementor-widget elementor-widget-nav-menu\" data-id=\"9bc3a56\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;layout&quot;:&quot;horizontal&quot;,&quot;submenu_icon&quot;:{&quot;value&quot;:&quot;&lt;i class=\\&quot;fas fa-caret-down\\&quot; aria-hidden=\\&quot;true\\&quot;&gt;&lt;\\\/i&gt;&quot;,&quot;library&quot;:&quot;fa-solid&quot;},&quot;toggle&quot;:&quot;burger&quot;}\" data-widget_type=\"nav-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<nav aria-label=\"Men\u00fc\" class=\"elementor-nav-menu--main elementor-nav-menu__container elementor-nav-menu--layout-horizontal e--pointer-underline e--animation-fade\">\n\t\t\t\t<ul id=\"menu-1-9bc3a56\" class=\"elementor-nav-menu\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-home menu-item-2384\"><a href=\"https:\/\/naturheilpraxis-kerres.de\/en\/\" class=\"elementor-item\">Home<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2017\"><a href=\"https:\/\/naturheilpraxis-kerres.de\/en\/notfallapotheke-fuer-tiere\/\" class=\"elementor-item\">Notfallapotheke f\u00fcr Tiere<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-914\"><a href=\"https:\/\/naturheilpraxis-kerres.de\/en\/homoeopathische-hausapotheke\/\" class=\"elementor-item\">Hom\u00f6opathische Hausapotheke<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-916\"><a href=\"https:\/\/naturheilpraxis-kerres.de\/en\/homoeopathie\/\" class=\"elementor-item\">Hom\u00f6opathie<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2553\"><a href=\"https:\/\/naturheilpraxis-kerres.de\/en\/healy-frequenztherapie\/\" class=\"elementor-item\">Healy-Frequenztherapie<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-915\"><a href=\"https:\/\/naturheilpraxis-kerres.de\/en\/pferdeosteopathie\/\" class=\"elementor-item\">Pferdeosteopathie<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2671\"><a href=\"https:\/\/naturheilpraxis-kerres.de\/en\/empfehlungen\/\" class=\"elementor-item\">Empfehlungen<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2672\"><a href=\"https:\/\/naturheilpraxis-kerres.de\/en\/blog\/\" class=\"elementor-item\">Blog<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t<div class=\"elementor-menu-toggle\" role=\"button\" tabindex=\"0\" aria-label=\"Menu Toggle\" aria-expanded=\"false\">\n\t\t\t<i aria-hidden=\"true\" role=\"presentation\" class=\"elementor-menu-toggle__icon--open eicon-menu-bar\"><\/i><i aria-hidden=\"true\" role=\"presentation\" class=\"elementor-menu-toggle__icon--close eicon-close\"><\/i>\t\t<\/div>\n\t\t\t\t\t<nav class=\"elementor-nav-menu--dropdown elementor-nav-menu__container\" aria-hidden=\"true\">\n\t\t\t\t<ul id=\"menu-2-9bc3a56\" class=\"elementor-nav-menu\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-home menu-item-2384\"><a href=\"https:\/\/naturheilpraxis-kerres.de\/en\/\" class=\"elementor-item\" tabindex=\"-1\">Home<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2017\"><a href=\"https:\/\/naturheilpraxis-kerres.de\/en\/notfallapotheke-fuer-tiere\/\" class=\"elementor-item\" tabindex=\"-1\">Notfallapotheke f\u00fcr Tiere<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-914\"><a href=\"https:\/\/naturheilpraxis-kerres.de\/en\/homoeopathische-hausapotheke\/\" class=\"elementor-item\" tabindex=\"-1\">Hom\u00f6opathische Hausapotheke<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-916\"><a href=\"https:\/\/naturheilpraxis-kerres.de\/en\/homoeopathie\/\" class=\"elementor-item\" tabindex=\"-1\">Hom\u00f6opathie<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2553\"><a href=\"https:\/\/naturheilpraxis-kerres.de\/en\/healy-frequenztherapie\/\" class=\"elementor-item\" tabindex=\"-1\">Healy-Frequenztherapie<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-915\"><a href=\"https:\/\/naturheilpraxis-kerres.de\/en\/pferdeosteopathie\/\" class=\"elementor-item\" tabindex=\"-1\">Pferdeosteopathie<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2671\"><a href=\"https:\/\/naturheilpraxis-kerres.de\/en\/empfehlungen\/\" class=\"elementor-item\" tabindex=\"-1\">Empfehlungen<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2672\"><a href=\"https:\/\/naturheilpraxis-kerres.de\/en\/blog\/\" class=\"elementor-item\" tabindex=\"-1\">Blog<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1826f9e9 elementor-section-full_width elementor-section-height-min-height elementor-section-height-default elementor-section-items-middle\" data-id=\"1826f9e9\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-66647a51\" data-id=\"66647a51\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-757de656 elementor-widget elementor-widget-heading\" data-id=\"757de656\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Die 10 wichtigsten Mittel f\u00fcr die hom\u00f6opathische Hausapotheke<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2d3b59eb elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"2d3b59eb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Mit diesen 10 Mitteln bist du einfach auf alles vorbereitet<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7bd2481 elementor-mobile-align-center elementor-align-center elementor-hidden-mobile elementor-widget elementor-widget-button\" data-id=\"7bd2481\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjMyNSIsInRvZ2dsZSI6ZmFsc2V9\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-angle-double-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Zum kostenfreien Ratgeber<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5693eaf elementor-mobile-align-center elementor-align-center elementor-hidden-desktop elementor-hidden-tablet elementor-widget elementor-widget-button\" data-id=\"5693eaf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjEyMDYiLCJ0b2dnbGUiOmZhbHNlfQ%3D%3D\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-angle-double-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Ratgeber Hom\u00f6opathische Hausapotheke<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-35b7a712 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"35b7a712\" data-element_type=\"section\" data-e-type=\"section\" id=\"next\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e295188\" data-id=\"e295188\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-414bf86b elementor-widget elementor-widget-heading\" data-id=\"414bf86b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Du profitierst von diesem Erfahrungsschatz:<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b0c2774 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b0c2774\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-7069973\" data-id=\"7069973\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a7e6c18 elementor-widget elementor-widget-icon-box\" data-id=\"a7e6c18\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tJahrzehntelange Erfahrung\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tSeit 20 Jahren Tierheilpraktikerin und Heilpraktikerin f\u00fcr Mensch und Tier\n    Ausbildung an der International School for Classical Homeopathy in Hechtel\/Belgien bei\n    Dr. Alfons Geukens, einem der bekanntesten Hom\u00f6opathen der Gegenwart.\n\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-be0c88d\" data-id=\"be0c88d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3c55dfd elementor-widget elementor-widget-icon-box\" data-id=\"3c55dfd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tBekannte Referentin und Autorin\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tVortr\u00e4ge im Laufe der Jahre \u00fcber hom\u00f6opathische Notfallapotheken f\u00fcr Mensch &amp; Tier, Bachbl\u00fcten und Sch\u00fcsslersalze u.a. bei Tierseminar.de und Autorin bei hunderunden.de.\n\n\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-7f2cd90\" data-id=\"7f2cd90\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4b934d3 elementor-widget elementor-widget-icon-box\" data-id=\"4b934d3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\t&gt;3.000 Behandlungen\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tEin riesiger Erfahrungsschatz durch die Behandlung von mehreren 1000 Mensch- und Tierpatienten in 20 Jahren Praxist\u00e4tigkeit.\n\n\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8aad299 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8aad299\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-56a224b\" data-id=\"56a224b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d8ad82a elementor-widget elementor-widget-text-editor\" data-id=\"d8ad82a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Mit diesem Ratgeber steht dir eine hom\u00f6opathische Hausapotheke zur Verf\u00fcgung f\u00fcr die h\u00e4ufigsten Alltagsbeschwerden.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2ebf3e7 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"2ebf3e7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9bb92b5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9bb92b5\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3a89a8e\" data-id=\"3a89a8e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c675e0c elementor-widget elementor-widget-heading\" data-id=\"c675e0c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Im Ratgeber verrate ich dir...<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f589641 elementor-widget elementor-widget-heading\" data-id=\"f589641\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">10 hom\u00f6opathische Mittel,<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dba4d7d elementor-widget elementor-widget-heading\" data-id=\"dba4d7d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">die in deiner Hausapotheke einfach nicht fehlen d\u00fcrfen<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-34c89e3 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"34c89e3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f4595c1 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"f4595c1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Einblick in die 10 wichtigsten Mittel f\u00fcr die hom\u00f6opathische Hausapotheke<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e5cd8a1 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"e5cd8a1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Von A wie Augenbindehautentz\u00fcndung bis Z wie Zerrung<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b205576 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"b205576\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Schnell der Weg zum passenden Mittel<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1b2ae59 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"1b2ae59\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Hilfestellung, welches Mittel das richtige f\u00fcr welche Beschwerden ist und wie Sie sie anwenden.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d7bb85c elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"d7bb85c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Einfache und sichere Anwendung<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-336dec7 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"336dec7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">F\u00fcr die ganze Familie und deine Tiere geeignet<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2e8a8175 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2e8a8175\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3a3b6106\" data-id=\"3a3b6106\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7b59f366 elementor-widget elementor-widget-heading\" data-id=\"7b59f366\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">Es funktioniert wirklich!<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-6193226f elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"6193226f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-704f321e\" data-id=\"704f321e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-21dd7755 elementor-widget elementor-widget-image\" data-id=\"21dd7755\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/naturheilpraxis-kerres.de\/wp-content\/uploads\/elementor\/thumbs\/Bianka-Bild-statt-Elisabeth-r3o5so7bw1b25bdu7ceeft5kofr30notqel8o1z5xs.png\" title=\"Dalmatiner von Elisabeth\" alt=\"Dalmatiner\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1e673b33 elementor--star-style-star_unicode elementor-star-rating--align-center elementor-widget elementor-widget-star-rating\" data-id=\"1e673b33\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"star-rating.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-star-rating__wrapper\">\n\t\t\t\t\t\t<div class=\"elementor-star-rating\" itemtype=\"http:\/\/schema.org\/Rating\" itemscope=\"\" itemprop=\"reviewRating\">\n\t\t\t\t<i class=\"elementor-star-full\" aria-hidden=\"true\">&#9733;<\/i><i class=\"elementor-star-full\" aria-hidden=\"true\">&#9733;<\/i><i class=\"elementor-star-full\" aria-hidden=\"true\">&#9733;<\/i><i class=\"elementor-star-full\" aria-hidden=\"true\">&#9733;<\/i><i class=\"elementor-star-full\" aria-hidden=\"true\">&#9733;<\/i>\t\t\t\t<span itemprop=\"ratingValue\" class=\"elementor-screen-only\">Bewertet mit 5 von 5<\/span>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-19549bb0 elementor-widget elementor-widget-testimonial\" data-id=\"19549bb0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"testimonial.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial-wrapper\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial-content\">\"Ich nutze meine hom\u00f6opathische Hausapotheke st\u00e4ndig! Irgendwas ist doch immer, ob eine\nMagenverstimmung oder ein Insektenstich. Mit dem passenden hom\u00f6opathischen Mittel aus der\nHausapotheke bekommen wir die meisten Beschwerden in den Griff und ich habe auch immer was\nzur Hand f\u00fcr meine Enkelkinder und f\u00fcr meine Mutter, die immerhin schon \u00fcber 90 Jahre alt ist!\"<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-testimonial-meta\">\n\t\t\t\t<div class=\"elementor-testimonial-meta-inner\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial-details\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial-name\">Elisabeth W.<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-26a00d51\" data-id=\"26a00d51\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6fb92470 elementor-widget elementor-widget-image\" data-id=\"6fb92470\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/naturheilpraxis-kerres.de\/wp-content\/uploads\/elementor\/thumbs\/Referenz-Hermann-Josef-pjwvnjqz1401tly8vc2uewn02u7mvpmsc47dscqbps.jpeg\" title=\"Referenz Hermann-Josef\" alt=\"Referenz Hermann-Josef\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5496c76e elementor--star-style-star_unicode elementor-star-rating--align-center elementor-widget elementor-widget-star-rating\" data-id=\"5496c76e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"star-rating.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-star-rating__wrapper\">\n\t\t\t\t\t\t<div class=\"elementor-star-rating\" itemtype=\"http:\/\/schema.org\/Rating\" itemscope=\"\" itemprop=\"reviewRating\">\n\t\t\t\t<i class=\"elementor-star-full\" aria-hidden=\"true\">&#9733;<\/i><i class=\"elementor-star-full\" aria-hidden=\"true\">&#9733;<\/i><i class=\"elementor-star-full\" aria-hidden=\"true\">&#9733;<\/i><i class=\"elementor-star-full\" aria-hidden=\"true\">&#9733;<\/i><i class=\"elementor-star-full\" aria-hidden=\"true\">&#9733;<\/i>\t\t\t\t<span itemprop=\"ratingValue\" class=\"elementor-screen-only\">Bewertet mit 5 von 5<\/span>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4b78b502 elementor-widget elementor-widget-testimonial\" data-id=\"4b78b502\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"testimonial.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial-wrapper\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial-content\">\"Unsere hom\u00f6opathische Hausapotheke ist unser st\u00e4ndiger Begleiter im Alltag und auf unseren\nReisen. So konnten wir uns schon h\u00e4ufig selber schnell helfen. Und auch f\u00fcr unseren Hund k\u00f6nnen\nwir die Mittel anwenden, so k\u00f6nnen wir Kleinigkeiten immer schnell und sicher mit den\nNotfallmitteln behandeln!\"<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-testimonial-meta\">\n\t\t\t\t<div class=\"elementor-testimonial-meta-inner\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial-details\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial-name\">Hermann-Josef H.<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-196ef41c\" data-id=\"196ef41c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7cb5be8b elementor-widget elementor-widget-image\" data-id=\"7cb5be8b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/naturheilpraxis-kerres.de\/wp-content\/uploads\/elementor\/thumbs\/Referenz-Maroon-W._Klein-pkxjw3a2d8zqyu3akb54nqsutm2q4znh8k6s7for0w.jpg\" title=\"Referenz Maroon W._Klein\" alt=\"Referenz Maroon W._Klein\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-27fc01d6 elementor--star-style-star_unicode elementor-star-rating--align-center elementor-widget elementor-widget-star-rating\" data-id=\"27fc01d6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"star-rating.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-star-rating__wrapper\">\n\t\t\t\t\t\t<div class=\"elementor-star-rating\" itemtype=\"http:\/\/schema.org\/Rating\" itemscope=\"\" itemprop=\"reviewRating\">\n\t\t\t\t<i class=\"elementor-star-full\" aria-hidden=\"true\">&#9733;<\/i><i class=\"elementor-star-full\" aria-hidden=\"true\">&#9733;<\/i><i class=\"elementor-star-full\" aria-hidden=\"true\">&#9733;<\/i><i class=\"elementor-star-full\" aria-hidden=\"true\">&#9733;<\/i><i class=\"elementor-star-full\" aria-hidden=\"true\">&#9733;<\/i>\t\t\t\t<span itemprop=\"ratingValue\" class=\"elementor-screen-only\">Bewertet mit 5 von 5<\/span>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-25b2b5ad elementor-widget elementor-widget-testimonial\" data-id=\"25b2b5ad\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"testimonial.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial-wrapper\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial-content\">\u201cDa ich schon als Kind mit Globuli behandelt wurde ist es auch heute f\u00fcr mich selbstverst\u00e4ndlich, dass ich hom\u00f6opathische Mittel nutze. Darum habe ich alle Mittel der hom\u00f6opathischen Hausapotheke zu Hause und wann immer ich etwas habe schaue ich zuerst in meinen Ratgeber. So kann ich mir in den meisten F\u00e4llen schnell selber helfen. \u201d<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-testimonial-meta\">\n\t\t\t\t<div class=\"elementor-testimonial-meta-inner\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial-details\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial-name\">Maroon W.<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2c62258 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2c62258\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-5032341\" data-id=\"5032341\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-11e75b55 elementor-widget elementor-widget-image\" data-id=\"11e75b55\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"558\" height=\"592\" src=\"https:\/\/naturheilpraxis-kerres.de\/wp-content\/uploads\/2022\/01\/MockUp-Homoeopathische-Mittel.jpg\" class=\"attachment-full size-full wp-image-208\" alt=\"\" srcset=\"https:\/\/naturheilpraxis-kerres.de\/wp-content\/uploads\/2022\/01\/MockUp-Homoeopathische-Mittel.jpg 558w, https:\/\/naturheilpraxis-kerres.de\/wp-content\/uploads\/2022\/01\/MockUp-Homoeopathische-Mittel-283x300.jpg 283w\" sizes=\"(max-width: 558px) 100vw, 558px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-4c70826\" data-id=\"4c70826\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2587d5c elementor-mobile-align-center elementor-align-center elementor-hidden-mobile elementor-widget elementor-widget-button\" data-id=\"2587d5c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjMyNSIsInRvZ2dsZSI6ZmFsc2V9\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-angle-double-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Zum kostenfreien Ratgeber<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b2fa0f5 elementor-mobile-align-center elementor-align-center elementor-hidden-desktop elementor-hidden-tablet elementor-widget elementor-widget-button\" data-id=\"b2fa0f5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjEyMDYiLCJ0b2dnbGUiOmZhbHNlfQ%3D%3D\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-angle-double-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Ratgeber Hom\u00f6opathische Hausapotheke<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2feedbd8 elementor-section-height-min-height elementor-section-items-stretch elementor-section-boxed elementor-section-height-default\" data-id=\"2feedbd8\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;slideshow&quot;,&quot;background_slideshow_gallery&quot;:[{&quot;id&quot;:174,&quot;url&quot;:&quot;https:\\\/\\\/naturheilpraxis-kerres.de\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/Bianka-mit-Pferd-scaled.jpg&quot;},{&quot;id&quot;:175,&quot;url&quot;:&quot;https:\\\/\\\/naturheilpraxis-kerres.de\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/Hunde.jpg&quot;}],&quot;background_slideshow_slide_duration&quot;:3000,&quot;background_slideshow_ken_burns&quot;:&quot;yes&quot;,&quot;background_slideshow_ken_burns_zoom_direction&quot;:&quot;out&quot;,&quot;background_slideshow_loop&quot;:&quot;yes&quot;,&quot;background_slideshow_slide_transition&quot;:&quot;fade&quot;,&quot;background_slideshow_transition_duration&quot;:500}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-610dc003\" data-id=\"610dc003\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7ffeaccc elementor-widget elementor-widget-heading\" data-id=\"7ffeaccc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u00dcber mich<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-81fcf09 elementor-widget elementor-widget-text-editor\" data-id=\"81fcf09\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Mein Name ist Bianka Kerres und mein Interesse an Naturheilkunde und im Speziellen f\u00fcr die Hom\u00f6opathie wurde schon w\u00e4hrend meines Musikstudiums geweckt. Durch immer wiederkehrende Blasenentz\u00fcndungen suchte ich damals zum ersten Mal eine Heilpraktikerin f\u00fcr Klassische Hom\u00f6opathie auf, die mich durch die Gabe von nur einem Mittel von meinen Beschwerden befreite.<br \/>Und das f\u00fcr immer!<\/p><p>Als ich dann bei mir zu Hause eine streunende Katze aufgenommen habe, die unter Schnupfen litt und ich auch dieser mit Globuli helfen konnte, entstand der Wunsch mir dieses Wissen selber anzueignen. Also entschloss ich mich, zun\u00e4chst eine Tierheilpraktiker-Ausbildung zu machen. Im Anschluss folgte noch eine Ausbildung f\u00fcr Pferdeosteopathie, f\u00fcr Klassische Hom\u00f6opathie in Belgien und die gro\u00dfe Heilpraktiker Ausbildung.<\/p><p>Seit 20 Jahren praktiziere ich nun mit Schwerpunkt Klassische Hom\u00f6opathie und Frequenztherapie und habe seitdem mehrere 1000 Menschen und Tiere in meiner Praxis behandelt.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-456589d elementor-mobile-align-center elementor-align-center elementor-hidden-mobile elementor-widget elementor-widget-button\" data-id=\"456589d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjMyNSIsInRvZ2dsZSI6ZmFsc2V9\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-angle-double-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Zum kostenfreien Ratgeber<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dee3f8a elementor-mobile-align-center elementor-align-center elementor-hidden-desktop elementor-hidden-tablet elementor-widget elementor-widget-button\" data-id=\"dee3f8a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjEyMDYiLCJ0b2dnbGUiOmZhbHNlfQ%3D%3D\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-angle-double-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Ratgeber Hom\u00f6opathische Hausapotheke<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-087e717 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"087e717\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-0e7f347\" data-id=\"0e7f347\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2af9ac5 elementor-icon-list--layout-inline elementor-align-center elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"2af9ac5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items elementor-inline-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/naturheilpraxis-kerres.de\/datenschutz\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Datenschutz<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/naturheilpraxis-kerres.de\/impressum\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Impressum<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/naturheilpraxis-kerres.de\/ueber-mich\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\u00dcber mich<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/naturheilpraxis-kerres.de\/kontakt\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Kontakt<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-7eb672b\" data-id=\"7eb672b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ef63dd7 elementor-shape-rounded elementor-grid-0 e-grid-align-center elementor-widget elementor-widget-social-icons\" data-id=\"ef63dd7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"social-icons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-social-icons-wrapper elementor-grid\" role=\"list\">\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-facebook elementor-repeater-item-fbce6df\" href=\"https:\/\/www.facebook.com\/naturheilpraxiskerres\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Facebook<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-facebook\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-instagram elementor-repeater-item-c46a300\" href=\"https:\/\/www.instagram.com\/naturheilpraxiskerres\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Instagram<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-instagram\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Die 10 wichtigsten Mittel f\u00fcr die hom\u00f6opathische Hausapotheke Mit diesen 10 Mitteln bist du einfach auf alles vorbereitet Zum kostenfreien Ratgeber Ratgeber Hom\u00f6opathische Hausapotheke Du profitierst von diesem Erfahrungsschatz: Jahrzehntelange Erfahrung Seit 20 Jahren Tierheilpraktikerin und Heilpraktikerin f\u00fcr Mensch und Tier Ausbildung an der International School for Classical Homeopathy in Hechtel\/Belgien bei Dr. Alfons Geukens, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":191,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"open","template":"elementor_canvas","meta":{"footnotes":""},"class_list":["post-2","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Hom\u00f6opathische Hausapotheke - Naturheilpraxis<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hom\u00f6opathische Hausapotheke - Naturheilpraxis\" \/>\n<meta property=\"og:description\" content=\"Die 10 wichtigsten Mittel f\u00fcr die hom\u00f6opathische Hausapotheke Mit diesen 10 Mitteln bist du einfach auf alles vorbereitet Zum kostenfreien Ratgeber Ratgeber Hom\u00f6opathische Hausapotheke Du profitierst von diesem Erfahrungsschatz: Jahrzehntelange Erfahrung Seit 20 Jahren Tierheilpraktikerin und Heilpraktikerin f\u00fcr Mensch und Tier Ausbildung an der International School for Classical Homeopathy in Hechtel\/Belgien bei Dr. Alfons Geukens, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/naturheilpraxis-kerres.de\/en\/homoeopathische-hausapotheke\/\" \/>\n<meta property=\"og:site_name\" content=\"Naturheilpraxis\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-17T14:35:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/naturheilpraxis-kerres.de\/wp-content\/uploads\/2022\/01\/Header-Homoeopathische-Mittel-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1920\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/naturheilpraxis-kerres.de\\\/homoeopathische-hausapotheke\\\/\",\"url\":\"https:\\\/\\\/naturheilpraxis-kerres.de\\\/homoeopathische-hausapotheke\\\/\",\"name\":\"Hom\u00f6opathische Hausapotheke - Naturheilpraxis\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/naturheilpraxis-kerres.de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/naturheilpraxis-kerres.de\\\/homoeopathische-hausapotheke\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/naturheilpraxis-kerres.de\\\/homoeopathische-hausapotheke\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/naturheilpraxis-kerres.de\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/Header-Homoeopathische-Mittel-scaled.jpg\",\"datePublished\":\"2022-01-21T16:15:24+00:00\",\"dateModified\":\"2025-06-17T14:35:24+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/naturheilpraxis-kerres.de\\\/homoeopathische-hausapotheke\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/naturheilpraxis-kerres.de\\\/homoeopathische-hausapotheke\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/naturheilpraxis-kerres.de\\\/homoeopathische-hausapotheke\\\/#primaryimage\",\"url\":\"https:\\\/\\\/naturheilpraxis-kerres.de\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/Header-Homoeopathische-Mittel-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/naturheilpraxis-kerres.de\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/Header-Homoeopathische-Mittel-scaled.jpg\",\"width\":2560,\"height\":1920},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/naturheilpraxis-kerres.de\\\/homoeopathische-hausapotheke\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/naturheilpraxis-kerres.de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Hom\u00f6opathische Hausapotheke\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/naturheilpraxis-kerres.de\\\/#website\",\"url\":\"https:\\\/\\\/naturheilpraxis-kerres.de\\\/\",\"name\":\"Naturheilpraxis\",\"description\":\"Naturheilpraxis Kerres - Hom\u00f6opathie f\u00fcr Mensch und Tier\",\"publisher\":{\"@id\":\"https:\\\/\\\/naturheilpraxis-kerres.de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/naturheilpraxis-kerres.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/naturheilpraxis-kerres.de\\\/#organization\",\"name\":\"Naturheilpraxis\",\"url\":\"https:\\\/\\\/naturheilpraxis-kerres.de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/naturheilpraxis-kerres.de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/naturheilpraxis-kerres.de\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/cropped-Favicon-Bianka-Kerres-Gross.png\",\"contentUrl\":\"https:\\\/\\\/naturheilpraxis-kerres.de\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/cropped-Favicon-Bianka-Kerres-Gross.png\",\"width\":500,\"height\":500,\"caption\":\"Naturheilpraxis\"},\"image\":{\"@id\":\"https:\\\/\\\/naturheilpraxis-kerres.de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Hom\u00f6opathische Hausapotheke - Naturheilpraxis","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"en_US","og_type":"article","og_title":"Hom\u00f6opathische Hausapotheke - Naturheilpraxis","og_description":"Die 10 wichtigsten Mittel f\u00fcr die hom\u00f6opathische Hausapotheke Mit diesen 10 Mitteln bist du einfach auf alles vorbereitet Zum kostenfreien Ratgeber Ratgeber Hom\u00f6opathische Hausapotheke Du profitierst von diesem Erfahrungsschatz: Jahrzehntelange Erfahrung Seit 20 Jahren Tierheilpraktikerin und Heilpraktikerin f\u00fcr Mensch und Tier Ausbildung an der International School for Classical Homeopathy in Hechtel\/Belgien bei Dr. Alfons Geukens, [&hellip;]","og_url":"https:\/\/naturheilpraxis-kerres.de\/en\/homoeopathische-hausapotheke\/","og_site_name":"Naturheilpraxis","article_modified_time":"2025-06-17T14:35:24+00:00","og_image":[{"width":2560,"height":1920,"url":"https:\/\/naturheilpraxis-kerres.de\/wp-content\/uploads\/2022\/01\/Header-Homoeopathische-Mittel-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/naturheilpraxis-kerres.de\/homoeopathische-hausapotheke\/","url":"https:\/\/naturheilpraxis-kerres.de\/homoeopathische-hausapotheke\/","name":"Hom\u00f6opathische Hausapotheke - Naturheilpraxis","isPartOf":{"@id":"https:\/\/naturheilpraxis-kerres.de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/naturheilpraxis-kerres.de\/homoeopathische-hausapotheke\/#primaryimage"},"image":{"@id":"https:\/\/naturheilpraxis-kerres.de\/homoeopathische-hausapotheke\/#primaryimage"},"thumbnailUrl":"https:\/\/naturheilpraxis-kerres.de\/wp-content\/uploads\/2022\/01\/Header-Homoeopathische-Mittel-scaled.jpg","datePublished":"2022-01-21T16:15:24+00:00","dateModified":"2025-06-17T14:35:24+00:00","breadcrumb":{"@id":"https:\/\/naturheilpraxis-kerres.de\/homoeopathische-hausapotheke\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/naturheilpraxis-kerres.de\/homoeopathische-hausapotheke\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/naturheilpraxis-kerres.de\/homoeopathische-hausapotheke\/#primaryimage","url":"https:\/\/naturheilpraxis-kerres.de\/wp-content\/uploads\/2022\/01\/Header-Homoeopathische-Mittel-scaled.jpg","contentUrl":"https:\/\/naturheilpraxis-kerres.de\/wp-content\/uploads\/2022\/01\/Header-Homoeopathische-Mittel-scaled.jpg","width":2560,"height":1920},{"@type":"BreadcrumbList","@id":"https:\/\/naturheilpraxis-kerres.de\/homoeopathische-hausapotheke\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/naturheilpraxis-kerres.de\/"},{"@type":"ListItem","position":2,"name":"Hom\u00f6opathische Hausapotheke"}]},{"@type":"WebSite","@id":"https:\/\/naturheilpraxis-kerres.de\/#website","url":"https:\/\/naturheilpraxis-kerres.de\/","name":"Naturopathic practice","description":"Naturheilpraxis Kerres - Hom\u00f6opathie f\u00fcr Mensch und Tier","publisher":{"@id":"https:\/\/naturheilpraxis-kerres.de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/naturheilpraxis-kerres.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/naturheilpraxis-kerres.de\/#organization","name":"Naturopathic practice","url":"https:\/\/naturheilpraxis-kerres.de\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/naturheilpraxis-kerres.de\/#\/schema\/logo\/image\/","url":"https:\/\/naturheilpraxis-kerres.de\/wp-content\/uploads\/2025\/04\/cropped-Favicon-Bianka-Kerres-Gross.png","contentUrl":"https:\/\/naturheilpraxis-kerres.de\/wp-content\/uploads\/2025\/04\/cropped-Favicon-Bianka-Kerres-Gross.png","width":500,"height":500,"caption":"Naturheilpraxis"},"image":{"@id":"https:\/\/naturheilpraxis-kerres.de\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/naturheilpraxis-kerres.de\/en\/wp-json\/wp\/v2\/pages\/2","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/naturheilpraxis-kerres.de\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/naturheilpraxis-kerres.de\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/naturheilpraxis-kerres.de\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/naturheilpraxis-kerres.de\/en\/wp-json\/wp\/v2\/comments?post=2"}],"version-history":[{"count":343,"href":"https:\/\/naturheilpraxis-kerres.de\/en\/wp-json\/wp\/v2\/pages\/2\/revisions"}],"predecessor-version":[{"id":2721,"href":"https:\/\/naturheilpraxis-kerres.de\/en\/wp-json\/wp\/v2\/pages\/2\/revisions\/2721"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/naturheilpraxis-kerres.de\/en\/wp-json\/wp\/v2\/media\/191"}],"wp:attachment":[{"href":"https:\/\/naturheilpraxis-kerres.de\/en\/wp-json\/wp\/v2\/media?parent=2"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}